{"id":1974,"date":"2026-05-07T17:59:59","date_gmt":"2026-05-07T14:59:59","guid":{"rendered":"https:\/\/www.menu.mirayhotelkleopatra.com\/?page_id=1974"},"modified":"2026-05-07T18:01:26","modified_gmt":"2026-05-07T15:01:26","slug":"biralar","status":"publish","type":"page","link":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/biralar\/","title":{"rendered":"Beers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1974\" class=\"elementor elementor-1974\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-964651f e-con-full e-flex e-con e-parent\" data-id=\"964651f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66061b6 elementor-widget elementor-widget-heading\" data-id=\"66061b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 20-09-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Biralar<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c700bc e-con-full e-flex e-con e-parent\" data-id=\"9c700bc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6d675 elementor-grid-default elementor-grid-tablet-default elementor-grid-mobile-default elementor-widget elementor-widget-woofoo\" data-id=\"9a6d675\" data-element_type=\"widget\" data-settings=\"{&quot;woofoo_grid_columns&quot;:&quot;default&quot;,&quot;woofoo_grid_columns_tablet&quot;:&quot;default&quot;,&quot;woofoo_grid_columns_mobile&quot;:&quot;default&quot;,&quot;woofoo_product_column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;woofoo_product_column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_product_column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_product_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;woofoo_product_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_product_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_image_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_title_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_title_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_title_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_description_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_description_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_description_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_price_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;woofoo_price_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_price_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_button_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_button_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_button_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_rating_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_rating_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;woofoo_rating_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"woofoo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"woofoo-cat-tag-title\">\r\n                    <\/div>\r\n        <div class=\"woofoo-container woofoo-design-2\">\r\n                    <div class=\"woofoo-design-2\">\r\n            <!-- Product Highlight -->\r\n                        <div class=\"woofoo-item-container woofoo-highlight\">\r\n                <!-- Label -->\r\n                                <!-- Image & Icon -->\r\n                <div class=\"woofoo-img-icon-wrapper\">\r\n                    <!-- Image -->\r\n                                            <div class=\"woofoo-image\"><img decoding=\"async\" src=\"https:\/\/www.menu.mirayhotelkleopatra.com\/wp-content\/uploads\/2026\/05\/GDH2Artboard-2-copy-1.webp\"><\/div>\r\n                                    <\/div>\r\n                <!-- Product Content -->\r\n                <div class=\"woofoo-content\">\r\n                    <!-- Title & Price -->\r\n                    <div class=\"woofoo-title-price-wrapper\">\r\n                        <!-- Title -->\r\n                        <div class=\"woofoo-title-wrapper\">\r\n                            <h2 class=\"woofoo-title\">Efes 33 CL.<\/h2>\r\n                        <\/div>\r\n                        <!-- Title & Price Separator -->\r\n                        <div class=\"woofoo-separator\"><\/div>\r\n                        <!-- Currency Symbol -->\r\n                                                <div class=\"woofoo-price-wrapper\">\r\n                            <div class=\"woofoo-sale-price\">\r\n                                                                    <span class=\"woofoo-currency-symbol beforecurrency\"><\/span>\r\n                                    <div class=\"woofoo-price\">150,00 \u20ba<\/div> \r\n                                                            <\/div>\r\n                                                        <div class=\"woofoo-regular-price woofoo-line\">\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <!-- Description -->\r\n                    <div class=\"woofoo-description\">\r\n                        <p><\/p>\r\n                    <\/div>\r\n                    <!-- Rate & Button -->\r\n                    <div class=\"woofoo-rate-btn-wrapper\">\r\n                        <!-- Rating -->\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n                <div class=\"woofoo-design-2\">\r\n            <!-- Product Highlight -->\r\n                        <div class=\"woofoo-item-container woofoo-highlight\">\r\n                <!-- Label -->\r\n                                <!-- Image & Icon -->\r\n                <div class=\"woofoo-img-icon-wrapper\">\r\n                    <!-- Image -->\r\n                                            <div class=\"woofoo-image\"><img decoding=\"async\" src=\"https:\/\/www.menu.mirayhotelkleopatra.com\/wp-content\/uploads\/2026\/05\/GDH2Artboard-2-copy-1.webp\"><\/div>\r\n                                    <\/div>\r\n                <!-- Product Content -->\r\n                <div class=\"woofoo-content\">\r\n                    <!-- Title & Price -->\r\n                    <div class=\"woofoo-title-price-wrapper\">\r\n                        <!-- Title -->\r\n                        <div class=\"woofoo-title-wrapper\">\r\n                            <h2 class=\"woofoo-title\">Efes 50 CL.<\/h2>\r\n                        <\/div>\r\n                        <!-- Title & Price Separator -->\r\n                        <div class=\"woofoo-separator\"><\/div>\r\n                        <!-- Currency Symbol -->\r\n                                                <div class=\"woofoo-price-wrapper\">\r\n                            <div class=\"woofoo-sale-price\">\r\n                                                                    <span class=\"woofoo-currency-symbol beforecurrency\"><\/span>\r\n                                    <div class=\"woofoo-price\">200,00 \u20ba<\/div> \r\n                                                            <\/div>\r\n                                                        <div class=\"woofoo-regular-price woofoo-line\">\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <!-- Description -->\r\n                    <div class=\"woofoo-description\">\r\n                        <p><\/p>\r\n                    <\/div>\r\n                    <!-- Rate & Button -->\r\n                    <div class=\"woofoo-rate-btn-wrapper\">\r\n                        <!-- Rating -->\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n                <div class=\"woofoo-design-2\">\r\n            <!-- Product Highlight -->\r\n                        <div class=\"woofoo-item-container woofoo-highlight\">\r\n                <!-- Label -->\r\n                                <!-- Image & Icon -->\r\n                <div class=\"woofoo-img-icon-wrapper\">\r\n                    <!-- Image -->\r\n                                            <div class=\"woofoo-image\"><img decoding=\"async\" src=\"https:\/\/www.menu.mirayhotelkleopatra.com\/wp-content\/uploads\/2026\/05\/GDH2Artboard-2-copy-1.webp\"><\/div>\r\n                                    <\/div>\r\n                <!-- Product Content -->\r\n                <div class=\"woofoo-content\">\r\n                    <!-- Title & Price -->\r\n                    <div class=\"woofoo-title-price-wrapper\">\r\n                        <!-- Title -->\r\n                        <div class=\"woofoo-title-wrapper\">\r\n                            <h2 class=\"woofoo-title\">Miller<\/h2>\r\n                        <\/div>\r\n                        <!-- Title & Price Separator -->\r\n                        <div class=\"woofoo-separator\"><\/div>\r\n                        <!-- Currency Symbol -->\r\n                                                <div class=\"woofoo-price-wrapper\">\r\n                            <div class=\"woofoo-sale-price\">\r\n                                                                    <span class=\"woofoo-currency-symbol beforecurrency\"><\/span>\r\n                                    <div class=\"woofoo-price\">220,00 \u20ba<\/div> \r\n                                                            <\/div>\r\n                                                        <div class=\"woofoo-regular-price woofoo-line\">\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <!-- Description -->\r\n                    <div class=\"woofoo-description\">\r\n                        <p><\/p>\r\n                    <\/div>\r\n                    <!-- Rate & Button -->\r\n                    <div class=\"woofoo-rate-btn-wrapper\">\r\n                        <!-- Rating -->\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n                <div class=\"woofoo-design-2\">\r\n            <!-- Product Highlight -->\r\n                        <div class=\"woofoo-item-container woofoo-highlight\">\r\n                <!-- Label -->\r\n                                <!-- Image & Icon -->\r\n                <div class=\"woofoo-img-icon-wrapper\">\r\n                    <!-- Image -->\r\n                                            <div class=\"woofoo-image\"><img decoding=\"async\" src=\"https:\/\/www.menu.mirayhotelkleopatra.com\/wp-content\/uploads\/2026\/05\/GDH2Artboard-2-copy-1.webp\"><\/div>\r\n                                    <\/div>\r\n                <!-- Product Content -->\r\n                <div class=\"woofoo-content\">\r\n                    <!-- Title & Price -->\r\n                    <div class=\"woofoo-title-price-wrapper\">\r\n                        <!-- Title -->\r\n                        <div class=\"woofoo-title-wrapper\">\r\n                            <h2 class=\"woofoo-title\">Corona<\/h2>\r\n                        <\/div>\r\n                        <!-- Title & Price Separator -->\r\n                        <div class=\"woofoo-separator\"><\/div>\r\n                        <!-- Currency Symbol -->\r\n                                                <div class=\"woofoo-price-wrapper\">\r\n                            <div class=\"woofoo-sale-price\">\r\n                                                                    <span class=\"woofoo-currency-symbol beforecurrency\"><\/span>\r\n                                    <div class=\"woofoo-price\">250,00 \u20ba<\/div> \r\n                                                            <\/div>\r\n                                                        <div class=\"woofoo-regular-price woofoo-line\">\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <!-- Description -->\r\n                    <div class=\"woofoo-description\">\r\n                        <p><\/p>\r\n                    <\/div>\r\n                    <!-- Rate & Button -->\r\n                    <div class=\"woofoo-rate-btn-wrapper\">\r\n                        <!-- Rating -->\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n                <\/div>\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8fff540 e-flex e-con-boxed e-con e-parent\" data-id=\"8fff540\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6293dff elementor-widget elementor-widget-spacer\" data-id=\"6293dff\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 20-09-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d7b6b4 e-flex e-con-boxed e-con e-parent\" data-id=\"7d7b6b4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52d6422 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"52d6422\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.menu.mirayhotelkleopatra.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ana Men\u00fc<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Biralar Efes 33 CL. 150,00 \u20ba Efes 50 CL. 200,00 \u20ba Miller 220,00 \u20ba Corona 250,00 \u20ba Ana Men\u00fc<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1974","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/pages\/1974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/comments?post=1974"}],"version-history":[{"count":4,"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/pages\/1974\/revisions"}],"predecessor-version":[{"id":1978,"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/pages\/1974\/revisions\/1978"}],"wp:attachment":[{"href":"https:\/\/www.menu.mirayhotelkleopatra.com\/en\/wp-json\/wp\/v2\/media?parent=1974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}